{"id":13029,"date":"2026-05-12T09:22:18","date_gmt":"2026-05-12T15:22:18","guid":{"rendered":"https:\/\/peopleofcostarica.com\/?post_type=agenda&#038;p=13029"},"modified":"2026-05-12T09:22:18","modified_gmt":"2026-05-12T15:22:18","slug":"exposicion-cromografias-de-lo-imaginario-arte-musica-y-poesia-en-barrio-escalante","status":"publish","type":"agenda","link":"https:\/\/peopleofcostarica.com\/es\/agenda\/exposicion-cromografias-de-lo-imaginario-arte-musica-y-poesia-en-barrio-escalante\/","title":{"rendered":"Exposici\u00f3n Cromograf\u00edas de lo imaginario: arte, m\u00fasica y poes\u00eda en Barrio Escalante"},"content":{"rendered":"\n<p>La exposici\u00f3n <em>Cromograf\u00edas de lo imaginario<\/em> se inaugurar\u00e1 el <strong>14 de mayo de 2026<\/strong> en la <strong>Casa de la Cultura Banco Popular<\/strong> en <strong>Barrio Escalante<\/strong> (San Jos\u00e9). La muestra re\u00fane una propuesta <strong>multidisciplinaria<\/strong> del artista costarricense <strong>Johan Obando<\/strong>, con dibujos que exploran mundos imaginarios inspirados en la naturaleza, la fantas\u00eda y la sensibilidad emocional. Adem\u00e1s de las obras visuales, el evento contar\u00e1 con <strong>presentaciones musicales<\/strong> de la soprano l\u00edrica <strong>Sof\u00eda de la Cruz<\/strong> y espacios de <strong>poes\u00eda a cargo de Roberto Andr\u00e9 Acu\u00f1a<\/strong>, quien tambi\u00e9n fue curador de la exposici\u00f3n. La actividad, gratuita y abierta al p\u00fablico hasta el <strong>28 de mayo<\/strong>, busca generar un punto de encuentro entre diferentes manifestaciones art\u00edsticas y fomentar el intercambio cultural.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"featured_media":13030,"parent":0,"template":"","class_list":["post-13029","agenda","type-agenda","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/peopleofcostarica.com\/es\/wp-json\/wp\/v2\/agenda\/13029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peopleofcostarica.com\/es\/wp-json\/wp\/v2\/agenda"}],"about":[{"href":"https:\/\/peopleofcostarica.com\/es\/wp-json\/wp\/v2\/types\/agenda"}],"version-history":[{"count":1,"href":"https:\/\/peopleofcostarica.com\/es\/wp-json\/wp\/v2\/agenda\/13029\/revisions"}],"predecessor-version":[{"id":13031,"href":"https:\/\/peopleofcostarica.com\/es\/wp-json\/wp\/v2\/agenda\/13029\/revisions\/13031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/peopleofcostarica.com\/es\/wp-json\/wp\/v2\/media\/13030"}],"wp:attachment":[{"href":"https:\/\/peopleofcostarica.com\/es\/wp-json\/wp\/v2\/media?parent=13029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}